{"id":3076,"date":"2022-01-21T10:31:55","date_gmt":"2022-01-21T15:31:55","guid":{"rendered":"https:\/\/www.novaextermination.com\/realisations\/preventionen4\/"},"modified":"2022-01-21T10:31:55","modified_gmt":"2022-01-21T15:31:55","slug":"preventionen4","status":"publish","type":"realisations","link":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/","title":{"rendered":"preventionen4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2736,"template":"","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":""},"type_realisations":[94,99],"class_list":["post-3076","realisations","type-realisations","status-publish","has-post-thumbnail","hentry","type_realisations-job-type","type_realisations-prevention-services"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>preventionen4 - Nova Extermination<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"preventionen4 - Nova Extermination\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/\" \/>\n<meta property=\"og:site_name\" content=\"Nova Extermination\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/novaextermination\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.novaextermination.com\/wp-content\/uploads\/2022\/01\/Calfeutrage-Souris-Exterminateur6-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/\",\"url\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/\",\"name\":\"preventionen4 - Nova Extermination\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.novaextermination.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Calfeutrage-Souris-Exterminateur6-1.jpg\",\"datePublished\":\"2022-01-21T15:31:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.novaextermination.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Calfeutrage-Souris-Exterminateur6-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.novaextermination.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Calfeutrage-Souris-Exterminateur6-1.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/preventionen4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9alisations\",\"item\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/achievements\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"preventionen4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/\",\"name\":\"Nova Extermination\",\"description\":\"Exterminateur d&#039;insectes, de rongeurs et d&#039;animaux sur la Rive sud de Montr\u00e9al\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/#organization\",\"name\":\"Nova Extermination\",\"url\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.novaextermination.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/novaLogo.png\",\"contentUrl\":\"https:\\\/\\\/www.novaextermination.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/novaLogo.png\",\"width\":175,\"height\":72,\"caption\":\"Nova Extermination\"},\"image\":{\"@id\":\"https:\\\/\\\/www.novaextermination.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/novaextermination\\\/\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"preventionen4 - Nova Extermination","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/","og_locale":"en_US","og_type":"article","og_title":"preventionen4 - Nova Extermination","og_url":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/","og_site_name":"Nova Extermination","article_publisher":"https:\/\/www.facebook.com\/novaextermination\/","og_image":[{"width":500,"height":375,"url":"https:\/\/www.novaextermination.com\/wp-content\/uploads\/2022\/01\/Calfeutrage-Souris-Exterminateur6-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/","url":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/","name":"preventionen4 - Nova Extermination","isPartOf":{"@id":"https:\/\/www.novaextermination.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/#primaryimage"},"image":{"@id":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.novaextermination.com\/wp-content\/uploads\/2022\/01\/Calfeutrage-Souris-Exterminateur6-1.jpg","datePublished":"2022-01-21T15:31:55+00:00","breadcrumb":{"@id":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/#primaryimage","url":"https:\/\/www.novaextermination.com\/wp-content\/uploads\/2022\/01\/Calfeutrage-Souris-Exterminateur6-1.jpg","contentUrl":"https:\/\/www.novaextermination.com\/wp-content\/uploads\/2022\/01\/Calfeutrage-Souris-Exterminateur6-1.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/www.novaextermination.com\/en\/achievements\/preventionen4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.novaextermination.com\/en\/"},{"@type":"ListItem","position":2,"name":"R\u00e9alisations","item":"https:\/\/www.novaextermination.com\/en\/achievements\/"},{"@type":"ListItem","position":3,"name":"preventionen4"}]},{"@type":"WebSite","@id":"https:\/\/www.novaextermination.com\/en\/#website","url":"https:\/\/www.novaextermination.com\/en\/","name":"Nova Extermination","description":"Exterminateur d&#039;insectes, de rongeurs et d&#039;animaux sur la Rive sud de Montr\u00e9al","publisher":{"@id":"https:\/\/www.novaextermination.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.novaextermination.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/www.novaextermination.com\/en\/#organization","name":"Nova Extermination","url":"https:\/\/www.novaextermination.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.novaextermination.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.novaextermination.com\/wp-content\/uploads\/2021\/06\/novaLogo.png","contentUrl":"https:\/\/www.novaextermination.com\/wp-content\/uploads\/2021\/06\/novaLogo.png","width":175,"height":72,"caption":"Nova Extermination"},"image":{"@id":"https:\/\/www.novaextermination.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/novaextermination\/"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.novaextermination.com\/en\/wp-json\/wp\/v2\/realisations\/3076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaextermination.com\/en\/wp-json\/wp\/v2\/realisations"}],"about":[{"href":"https:\/\/www.novaextermination.com\/en\/wp-json\/wp\/v2\/types\/realisations"}],"version-history":[{"count":0,"href":"https:\/\/www.novaextermination.com\/en\/wp-json\/wp\/v2\/realisations\/3076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaextermination.com\/en\/wp-json\/wp\/v2\/media\/2736"}],"wp:attachment":[{"href":"https:\/\/www.novaextermination.com\/en\/wp-json\/wp\/v2\/media?parent=3076"}],"wp:term":[{"taxonomy":"type_realisations","embeddable":true,"href":"https:\/\/www.novaextermination.com\/en\/wp-json\/wp\/v2\/type_realisations?post=3076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}